{"id":8,"date":"2024-04-01T22:55:55","date_gmt":"2024-04-01T22:55:55","guid":{"rendered":"https:\/\/unsterblichkeit.eu\/wordpress\/?p=8"},"modified":"2024-04-01T23:04:27","modified_gmt":"2024-04-01T23:04:27","slug":"kapitel-02","status":"publish","type":"post","link":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/2024\/04\/01\/kapitel-02\/","title":{"rendered":"Kapitel 02"},"content":{"rendered":"\n<p>\u201eEin Kind, geboren aus strahlendem Licht. Eine Bindung, erwachsen aus der Tiefe unersch\u00fctterlicher Freundschaft. Geleitet vom Fl\u00fcstern der Vergangenheit werden sie das Verlorene aufsp\u00fcren und die Geschichte von morgen weben.\u201c<br>Undatierte Prophezeiung aus dem Buch &#8222;Vox Aeternitatis &#8211; Stimme der Ewigkeit&#8220; von Nostropheus aus dem 2. Sternenzyklus Wassermann. Archiviert im Astra Arcanum, der Bibliothek von Peria.<\/p>\n\n\n\n<p>Die Sonne goss ihr goldenes Licht \u00fcber Elstertal, w\u00e4hrend der Himmel ein makelloses Blau pr\u00e4sentierte. Das Lachen der Kinder durchbrach die Stille der bl\u00fchenden Blumenbeeten und tiefgr\u00fcnen Hecken.<br>Lina, Max und Tobi hatten sich eine schattige Bank erobert, die unter einem alten, knorrigen Baum stand. Ihre Stimmen vermischten sich mit dem Summen der Bienen und Zwitschern der V\u00f6gel, w\u00e4hrend sie sich angeregt unterhielten.<br>Lina lie\u00df ihre F\u00fc\u00dfe schaukeln, die Zehen ber\u00fchrten kaum den Boden, als sie Tobi mit einem funkelnden Blick ansah. &#8222;Glaubst du, eure Oma Lissy wird uns heute Abend wieder in eine ihrer magischen Geschichten entf\u00fchren?&#8220; Ihre Stimme tanzte vor Vorfreude.<br>Ein tr\u00e4umerisches L\u00e4cheln umspielte Tobis Lippen. &#8222;Oh das hoffe ich sehr! Ich liebe es, wenn sie von ihren magischen Abenteuern erz\u00e4hlt. Als ob all diese wunderbaren Kreaturen im Schatten unserer G\u00e4rten leben w\u00fcrden.&#8220;<br>Max&#8216; Blick verlor sich einen Moment lang in der Ferne, bevor er langsam nickte. Wie von unsichtbaren F\u00e4den gezogen, wanderte seine Hand in die Tiefe seiner Hosentasche und f\u00f6rderte eine alte, von feinen Kratzern \u00fcberzogene Taschenuhr zutage. Ein Erbst\u00fcck seines Opas, dessen Ber\u00fchrung ihn beruhigte. In Momenten, wenn er aufgew\u00fchlt war oder eine schwierige Situation in der Schule bew\u00e4ltigen musste, suchten seine Finger fast wie von selbst die glatte Oberfl\u00e4che der Uhr. Sie fuhren \u00fcber jede Vertiefung, jede Rundung und \u00fcber das glatte Glas. Oftmals war er sich dieses Rituals nicht einmal bewusst; seine Gedanken verloren sich und er konnte sich dann gar nicht daran erinnern sie in der Hand gehalten zu haben.<br>Die Erinnerung an den Gro\u00dfvater lie\u00df eine leise Sehnsucht in ihm aufkeimen. Lina, die Max&#8216; nachdenklichen Blick auffing, stupste ihn spielerisch an, &#8222;Erinnerst du dich an die Geschichte \u00fcber die F\u00fcchse?&#8220; Max runzelte die Stirn, ein Schmunzeln brach sich Bahn. &#8222;Die aetherischen F\u00fcchse, Lina, nicht einfach nur F\u00fcchse.&#8220; Lina imitierte ihn mit hochgezogenen Augenbrauen und einer \u00fcbertriebenen Mundbewegung, was Max und Tobi zum Lachen brachte. Ihre Albernheiten waren wie ein Sonnenstrahl, der die Schatten der tr\u00fcbsinnigen Gedanken verscheuchte.<br>\u201eLos kommt\u201c forderte Lina die beiden auf \u201eihr verpasst noch eure eigene Geburtstagsfeier!\u201c Diese Worte waren der Funke, der ihre Freunde in Bewegung setzte. Wie auf ein Zeichen sprangen sie gleichzeitig von der Bank und lie\u00dfen ihre Schritte zu einem hastigen, rhythmischen Trommeln auf dem festgetretenen Boden verschmelzen. Sie jagten dem gro\u00dfen, gr\u00fcnen Gartentor entgegen. Linas Hand traf das kalte Metall mit einem klaren hellen Ton, w\u00e4hrend sie laut &#8222;Erste!&#8220; rief. Ihr L\u00e4cheln breitete sich aus, als sie das Schild am Tor, das in eleganten, geschwungenen Buchstaben \u201eWillkommen bei Familie Wiesenbach\u201c verk\u00fcndete, mit einem leichten, verspielten Klaps begr\u00fc\u00dfte. Kurz nach ihr hasteten die beiden Geburtstagskinder ebenfalls durch das Tor und waren sichtlich beeindruckt, was ihre Eltern auf die Beine gestellt hatten.<br>Der Garten war geschm\u00fcckt mit verschiedenen gro\u00dfen und farbigen Luftballons. Auf einigen prangte stolz die Zahl 12, ein stilles Zeichen des heutigen Meilensteins.<br>Rundherum waren Tische und B\u00e4nke aufgebaut und der gro\u00dfe Familiengrill wartete darauf, angefeuert zu werden. Auf einem der Tische lockte eine gro\u00dfe Sch\u00fcssel Nudelsalat und daneben standen frisch aufgeschnittene Baguette-Stangen sowie ein gro\u00dfer Teller mit selbst gemachter Kr\u00e4uterbutter. Den Kindern lief bei dem Anblick das Wasser im Mund zusammen. Sie sahen sich um, ob sie beobachtet wurden, und griffen sich dann jeweils eine Scheibe Brot.<br>Eine glockenhelle Stimme hallte durch den Garten: &#8222;F\u00fcchse!&#8220; Augen weiteten sich, Herzen machten einen Sprung. Die Kinder drehten sich ruckartig um. &#8222;Wo?&#8220; entwich es ihren Lippen gleichzeitig. Oma Lissy, deren Augen listig funkelten, streckte ihre Arme aus, als wolle sie die ganze Welt umarmen. &#8222;Naschf\u00fcchse!&#8220; Ihr Lachen, warm und einladend, war wie immer ansteckend und die Kinder brachen in freudiges Gel\u00e4chter aus. Sie st\u00fcrmten auf Oma Lissy zu und umarmten sie in einem Wirbel aus Gl\u00fcck und Wiedersehensfreude.<br>Silberne Str\u00e4hnen, kunstvoll zu einem Zopf geflochten, umrahmten Lissys Gesicht, das von Falten durchzogen war, Zeugnisse eines langen, gelebten Lebens. Ihre Augen, weich und warm, wanderten von einem Kind zum n\u00e4chsten, als w\u00fcrde sie jeden einzelnen Moment mit ihnen einfangen wollen. &#8222;Wie sch\u00f6n, euch zu sehen. Wie geht es dir, Lina? Hast du mal wieder ein tolles Spiel erfunden?&#8220; Ihre Stimme, sanft und liebevoll, umh\u00fcllte die Kinder wie eine warme Decke. Elisabeth, die alle nur Oma Lissy nannten, hatte Lina seit ihrer Geburt in ihr gro\u00dfes, weiches Herz geschlossen. Die Kinder wuchsen praktisch wie Geschwister auf und verbrachten fast jede freie Minute miteinander, so dass sie ein dichtes Netz aus Erinnerungen und Abenteuern untrennbar miteinander verband. Die Eltern, Nachbarn und Freunde zugleich, beobachteten, wie die Kinder, Seite an Seite, durch Krippe und Kindergarten zogen, ein unzertrennliches Trio, das im Laufe der Jahre nur noch fester zusammenwuchs. In der Schule wurde schnell klar: Wer einen von ihnen herausforderte, bekam es mit allen zu tun. Lina, mutig und entschlossen, stand wie ein Schild vor den Zwillingen, bereit, jeden Kampf f\u00fcr sie zu k\u00e4mpfen. Ihre unersch\u00fctterliche Loyalit\u00e4t war das Band, das sie zusammenhielt, und die Jungs sch\u00e4tzten sie mehr als alles andere auf der Welt, entschlossen, alles zu tun, um ein L\u00e4cheln auf Linas Gesicht zu zaubern.<br>\u201eJa, habe ich tats\u00e4chlich! Ich nenne es Geschichten Memory.\u201c Lina strahlte \u00fcber das ganze Gesicht. \u201eHat dir dein Glitzerstein wieder seine Geheimnisse zugefl\u00fcstert und geholfen?\u201c, erkundigte sich Oma Lissy. Lina, deren Wangen sich in ein zartes Rosa f\u00e4rbten, nickte sch\u00fcchtern, ein leises &#8222;Ja&#8220; entwich ihren Lippen. Lissy beugte sich vor und fl\u00fcsterte verschw\u00f6rerisch \u201eDarf ich ihn noch einmal sehen?\u201c Begleitet von einem kichernden Glucksen verschwand Linas Hand an ihrem G\u00fcrtel und fand wie selbstverst\u00e4ndlich die kleine versteckte Geheimtasche. Sie tastete nach dem vertrauten kleinen Stein, der sich dort verbarg. Als sie ihn zwischen ihren Fingern f\u00fchlte, sp\u00fcrte sie sofort eine beruhigende W\u00e4rme, die sich durch ihren K\u00f6rper ausbreitete. Der Stein war klein und glatt, von einem zarten Rosa, das im Sonnenlicht schimmerte. In seinem Inneren schienen unz\u00e4hlige winzige Glitzerpartikel gefangen zu sein, die bei jeder Bewegung funkelten und tanzten, als w\u00fcrden sie eine eigene Geschichte erz\u00e4hlen. Lina hielt den Stein fest in ihrer Handfl\u00e4che und sp\u00fcrte, wie er sie mit seiner Pr\u00e4senz umh\u00fcllte, sie ermutigte und ihr Mut zusprach. Es war, als h\u00e4tte sie einen treuen Begleiter an ihrer Seite, der ihr in schwierigen Momenten Trost spendete und sie daran erinnerte, dass sie alles schaffen kann.<br>Vorsichtig \u00fcberreichte sie ihn Lissy, deren Augen sich im Glanz des Steines spiegelten. \u201eEr ist wundersch\u00f6n\u201c, fl\u00fcsterte Lissy ehrfurchtsvoll. \u201eDu musst ihn immer gut aufbewahren, er wird dir noch eine gro\u00dfe Hilfe sein!\u201c Sie legte den Stein genauso vorsichtig zur\u00fcck in Linas Hand, die kaum h\u00f6rbar aufatmete, als das kostbare Kleinod wieder in ihrem G\u00fcrtel verschwand.<br>Tobi, der das sonderbare Gespr\u00e4ch der Beiden beobachtet hatte, gab Lina einen z\u00e4rtlichen Knuff in die Seite \u201eUnsere Glitzerfee!\u201c und lief lachend zur\u00fcck zum Buffet, um sich eine weitere Scheibe Brot zu schnappen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eEin Kind, geboren aus strahlendem Licht. Eine Bindung, erwachsen aus der Tiefe unersch\u00fctterlicher Freundschaft. Geleitet vom Fl\u00fcstern der Vergangenheit werden sie das Verlorene aufsp\u00fcren und die Geschichte von morgen weben.\u201cUndatierte Prophezeiung aus dem Buch &#8222;Vox Aeternitatis &#8211; Stimme der Ewigkeit&#8220; von Nostropheus aus dem 2. Sternenzyklus Wassermann. Archiviert im Astra Arcanum, der Bibliothek von Peria. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[2],"tags":[6,7],"class_list":["post-8","post","type-post","status-publish","format-standard","hentry","category-kapitel","tag-final","tag-tera","entry"],"_links":{"self":[{"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":1,"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/8\/revisions"}],"predecessor-version":[{"id":9,"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/8\/revisions\/9"}],"wp:attachment":[{"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=8"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=8"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unsterblichkeit.eu\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}